{"id":8516,"date":"2026-09-01T13:01:19","date_gmt":"2026-09-01T11:01:19","guid":{"rendered":"https:\/\/www.laeroport.fr\/news\/marque-avions-ligne\/"},"modified":"2026-09-01T13:01:19","modified_gmt":"2026-09-01T11:01:19","slug":"marque-avions-ligne","status":"publish","type":"post","link":"https:\/\/www.laeroport.fr\/news\/marque-avions-ligne\/","title":{"rendered":"Ni Boeing ni Airbus : d\u00e9couvrez la marque \u00e9tonnante des deux avions de ligne pass\u00e9s tout pr\u00e8s du stade de rugby&#8230;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00c0 Cape Town, un \u00e9v\u00e9nement spectaculaire a boulevers\u00e9 les habitu\u00e9s du rugby et les amateurs d&rsquo;aviation commerciale. Deux avions de ligne sont pass\u00e9s \u00e0 seulement une douzaine de m\u00e8tres au-dessus du toit du DLC Stadium, venant fr\u00f4ler un public mass\u00e9 pour le match opposant les Springboks aux All Blacks. Ce survol \u00e9tonnant, qui a eu lieu le samedi 29 ao\u00fbt 2026, n\u2019a pas \u00e9t\u00e9 r\u00e9alis\u00e9 par les g\u00e9ants habituels du ciel tels que Boeing ou Airbus, mais par une marque a\u00e9ronautique moins connue du grand public : Embraer. Cet \u00e9pisode in\u00e9dit souligne l&rsquo;\u00e9volution des acteurs du transport a\u00e9rien et leur r\u00f4le croissant dans l&rsquo;aviation commerciale internationale, en particulier sur des march\u00e9s comme l&rsquo;Afrique du Sud.<\/p>\n\n<p class=\"wp-block-paragraph\">Les deux avions en question, un Embraer E190 et un E195, op\u00e8rent sous la banni\u00e8re d\u2019Airlink, une compagnie r\u00e9gionale d\u2019Afrique australe. Leur survol en formation \u00e0 tr\u00e8s basse altitude r\u00e9v\u00e8le non seulement une ma\u00eetrise technique impressionnante mais aussi la mont\u00e9e en puissance d\u2019une troisi\u00e8me force a\u00e9ronautique capable de rivaliser sur certains segments sp\u00e9cifiques avec les mastodontes am\u00e9ricains et europ\u00e9ens. Cette man\u0153uvre spectaculaire a suscit\u00e9 autant d\u2019admiration que de questions, tant elle s\u2019\u00e9carte des standards habituels des survols a\u00e9riens officiels.<\/p>\n\n<p class=\"wp-block-paragraph\">Loin d\u2019\u00eatre un simple spectacle, ce passage proche du stade illustre un changement de paradigme dans la comp\u00e9titivit\u00e9 et la diversit\u00e9 des constructeurs d\u2019avions de ligne. Pendant des d\u00e9cennies, la bataille commerciale et technologique s\u2019est concentr\u00e9e entre Boeing et Airbus, leader incontest\u00e9s, avec leurs produits massifs et long-courriers. Cependant, des manufactures comme Embraer ont su se distinguer en proposant des avions de taille moyenne et r\u00e9gionaux, id\u00e9aux pour des liaisons a\u00e9riennes efficaces et flexibles qui correspondent mieux \u00e0 certaines g\u00e9ographies et attentes des compagnies a\u00e9riennes.<\/p>\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie a\u00e9rienne au-dessus du DLC Stadium \u00e0 Cape Town focalise ainsi l&rsquo;attention sur une autre facette du transport a\u00e9rien, bien diff\u00e9rente des sc\u00e9narios souvent relay\u00e9s dans l\u2019actualit\u00e9 sur la p\u00e9nurie de k\u00e9ros\u00e8ne qui inqui\u00e8te plusieurs compagnies ou encore des d\u00e9fis logistiques li\u00e9s aux grands hubs europ\u00e9ens et am\u00e9ricains. Ce moment exceptionnel engage \u00e0 un regard neuf sur une industrie qui, malgr\u00e9 les tensions g\u00e9opolitiques et \u00e9conomiques, continue de surprendre et d\u2019innover.<\/p>\n\n<p class=\"wp-block-paragraph\">Alors que d&rsquo;autres \u00e9v\u00e9nements a\u00e9riens, comme la r\u00e9cente trajectoire quasi-collision entre un Boeing et un Airbus au-dessus de l&rsquo;Atlantique, font la Une des m\u00e9dias, le survol organis\u00e9 par Airlink rappelle que la ma\u00eetrise technique et les prouesses a\u00e9ronautiques peuvent prendre des formes vari\u00e9es, parfois bien en dehors des projecteurs traditionnels. En scrutant de plus pr\u00e8s ces avions de ligne issus d\u2019une marque \u00e9tonnante, il devient possible d\u2019observer comment la diversification des constructeurs enrichit le paysage de l\u2019aviation commerciale.<\/p>\n\n<h2 class=\"wp-block-heading\">Un regard d\u00e9taill\u00e9 sur Embraer : la marque a\u00e9ronautique qui s\u2019impose hors des g\u00e9ants Boeing et Airbus<\/h2>\n\n<p class=\"wp-block-paragraph\">Embraer, constructeur a\u00e9ronautique br\u00e9silien fond\u00e9 en 1969, a su se forger une renomm\u00e9e internationale en se sp\u00e9cialisant dans les avions r\u00e9gionaux et moyen-courriers. Contrairement \u00e0 Boeing et Airbus qui dominent surtout le segment des avions de plus grande envergure, la marque s\u2019est impos\u00e9e avec des appareils polyvalents, adapt\u00e9s aux contraintes g\u00e9ographiques et \u00e9conomiques de nombreuses r\u00e9gions \u00e0 travers le monde.<\/p>\n\n<p class=\"wp-block-paragraph\">Les deux avions survolant le stade \u00e0 Cape Town incarnent parfaitement cette philosophie. L\u2019Embraer E190 et son grand fr\u00e8re E195 sont des jets commerciaux capables d\u2019accueillir de 80 \u00e0 130 passagers, offrant une solution plus \u00e9conomique et agile pour les trajets courts ou moyens, notamment dans des zones o\u00f9 la demande ne justifie pas l\u2019utilisation d\u2019avions gros porteurs.<\/p>\n\n<p class=\"wp-block-paragraph\">Ce positionnement strat\u00e9gique s\u2019est traduit par de nombreux contrats avec des compagnies a\u00e9riennes r\u00e9gionales comme Airlink, qui dessert des destinations souvent en dehors des circuits traditionnels des grandes lignes internationales. Embraer s\u2019appuie sur des innovations technologiques, notamment l\u2019utilisation de mat\u00e9riaux composites et la r\u00e9duction de la consommation de carburant, pour r\u00e9pondre aux enjeux environnementaux et \u00e9conomiques actuels. En 2026, cette \u00e9volution est d\u2019autant plus critique que le secteur subit des pressions li\u00e9es \u00e0 la p\u00e9nurie de k\u00e9ros\u00e8ne ainsi qu\u2019\u00e0 des normes de plus en plus strictes impos\u00e9es par les autorit\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Par ailleurs, Embraer ne se limite plus uniquement aux avions r\u00e9gionaux. La marque a investi dans les jets d\u2019affaires et les avions militaires, ce qui lui permet d\u2019\u00e9tendre ses expertises et de diversifier ses sources de revenus. N\u00e9anmoins, au c\u0153ur du secteur civil, c\u2019est son r\u00f4le pionnier parmi les fabricants de tailles moyennes qui captive l\u2019attention, face \u00e0 la dualit\u00e9 souvent per\u00e7ue entre Boeing et Airbus. Ainsi, en observant de pr\u00e8s cette tierce voie, une compr\u00e9hension plus approfondie du paysage actuel du transport a\u00e9rien se dessine.<\/p>\n\n<p class=\"wp-block-paragraph\">L\u2019impact de ces appareils lors d\u2019\u00e9v\u00e9nements comme le survol \u00e0 Cape Town ne se limite pas \u00e0 un simple effet visuel : il souligne la confiance accrue que les compagnies r\u00e9gionales placent dans les avions de cette marque \u00e9tonnante, capables d\u2019assumer des missions pr\u00e9cises avec un excellent rapport qualit\u00e9-prix. Ce ph\u00e9nom\u00e8ne illustre \u00e9galement comment le march\u00e9 africain devient un terrain fertile pour des mod\u00e8les d\u2019affaires plus souples, en contraste avec les routes traditionnelles domin\u00e9es par les gros porteurs issus de Boeing et Airbus.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1344\" height=\"768\" src=\"https:\/\/www.laeroport.fr\/news\/wp-content\/uploads\/2026\/09\/Ni-Boeing-ni-Airbus-decouvrez-la-marque-etonnante-des-deux-avions-de-ligne-passes-tout-pres-du-stade-de-rugby-1.png\" alt=\"d\u00e9couvrez l&apos;histoire fascinante des deux avions de ligne, ni boeing ni airbus, qui ont survol\u00e9 de pr\u00e8s un stade de rugby, r\u00e9v\u00e9lant une marque \u00e9tonnante et m\u00e9connue.\" class=\"wp-image-8515\" srcset=\"https:\/\/www.laeroport.fr\/news\/wp-content\/uploads\/2026\/09\/Ni-Boeing-ni-Airbus-decouvrez-la-marque-etonnante-des-deux-avions-de-ligne-passes-tout-pres-du-stade-de-rugby-1.png 1344w, https:\/\/www.laeroport.fr\/news\/wp-content\/uploads\/2026\/09\/Ni-Boeing-ni-Airbus-decouvrez-la-marque-etonnante-des-deux-avions-de-ligne-passes-tout-pres-du-stade-de-rugby-1-300x171.png 300w, https:\/\/www.laeroport.fr\/news\/wp-content\/uploads\/2026\/09\/Ni-Boeing-ni-Airbus-decouvrez-la-marque-etonnante-des-deux-avions-de-ligne-passes-tout-pres-du-stade-de-rugby-1-1024x585.png 1024w, https:\/\/www.laeroport.fr\/news\/wp-content\/uploads\/2026\/09\/Ni-Boeing-ni-Airbus-decouvrez-la-marque-etonnante-des-deux-avions-de-ligne-passes-tout-pres-du-stade-de-rugby-1-768x439.png 768w\" sizes=\"auto, (max-width: 1344px) 100vw, 1344px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\">Les innovations technologiques sp\u00e9cifiques aux avions de marque Embraer<\/h3>\n\n<p class=\"wp-block-paragraph\">Embraer int\u00e8gre des syst\u00e8mes de derni\u00e8re g\u00e9n\u00e9ration dans ses avions de ligne, pens\u00e9s pour maximiser la s\u00e9curit\u00e9, la performance et le confort. Parmi les nouveaut\u00e9s, citons l\u2019optimisation a\u00e9rodynamique, des moteurs plus silencieux, ainsi qu\u2019un cockpit digitalis\u00e9 favorisant la r\u00e9duction de la charge de travail des pilotes. Ces caract\u00e9ristiques sont particuli\u00e8rement appr\u00e9ci\u00e9es dans l\u2019aviation commerciale r\u00e9gionale, o\u00f9 la fr\u00e9quence des vols est \u00e9lev\u00e9e et les marges parfois limit\u00e9es.<\/p>\n\n<p class=\"wp-block-paragraph\">Le recours \u00e0 des \u00e9quipements avioniques avanc\u00e9s, combin\u00e9 \u00e0 des structures l\u00e9g\u00e8res et robustes, permet \u00e0 Embraer de proposer des appareils adapt\u00e9s aux infrastructures a\u00e9roportuaires parfois limit\u00e9es, un facteur essentiel dans des r\u00e9gions comme l\u2019Afrique australe. Ainsi, la marque devient un choix strat\u00e9gique face aux contraintes logistiques, un avantage que Boeing et Airbus ne peuvent pas toujours offrir \u00e9quitablement sur ce terrain.<\/p>\n\n<h2 class=\"wp-block-heading\">Le survol du DLC Stadium \u00e0 Cape Town : un \u00e9v\u00e9nement in\u00e9dit pour l\u2019aviation commerciale<\/h2>\n\n<p class=\"wp-block-paragraph\">Le samedi 29 ao\u00fbt 2026 restera grav\u00e9 dans les m\u00e9moires comme la journ\u00e9e o\u00f9 deux avions de ligne se sont approch\u00e9s \u00e0 moins de 12 m\u00e8tres du toit d\u2019un stade de rugby d\u00e9bordant de spectateurs. Cet exploit est le fruit d\u2019une coordination exceptionnelle entre Airlink, les contr\u00f4leurs a\u00e9riens sud-africains et les pilotes, t\u00e9moignant de l\u2019expertise et de la ma\u00eetrise des technologies modernes en aviation.<\/p>\n\n<p class=\"wp-block-paragraph\">Survoler un stade en pleine activit\u00e9 sportive implique des contraintes de s\u00e9curit\u00e9 importantes et des autorisations sp\u00e9cifiques. Le choix de deux Embraer E190 et E195 illustre la confiance accord\u00e9e \u00e0 cette marque a\u00e9ronautique, capable d\u2019ex\u00e9cuter ce type de d\u00e9monstration sans mettre en p\u00e9ril l&rsquo;\u00e9v\u00e9nement ou le public. Ce moment a offert un spectacle rare \u00e0 des milliers de fans tout en promouvant l\u2019avancement technologique dans le voisinage d\u2019un complexe sportif majeur.<\/p>\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 de la performance a\u00e9rienne, cet \u00e9v\u00e9nement met en lumi\u00e8re le r\u00f4le croissant des acteurs \u00e9mergents dans l\u2019aviation commerciale. En Afrique, la demande pour des connexions r\u00e9gionales efficaces ne cesse de cro\u00eetre, soutenant ainsi la n\u00e9cessit\u00e9 de flottes diversifi\u00e9es et adaptables. Ce survol spectaculaire donne une image concr\u00e8te de cette transition o\u00f9 l\u2019essor de nouvelles marques permet d\u2019\u00e9largir le panorama a\u00e9rien vers des destinations moins desservies par les g\u00e9ants de Boeing ou Airbus.<\/p>\n\n<h3 class=\"wp-block-heading\">R\u00e9percussions sur le secteur du transport a\u00e9rien r\u00e9gional<\/h3>\n\n<p class=\"wp-block-paragraph\">Le choix de la compagnie Airlink pour cette d\u00e9monstration n\u2019est pas anodin. Acteur cl\u00e9 en Afrique australe, la compagnie mise sur l\u2019agilit\u00e9 et la modernit\u00e9 de sa flotte Embraer pour s\u2019adapter \u00e0 une dynamique \u00e9conomique et g\u00e9opolitique complexe. Son mod\u00e8le illustre une orientation strat\u00e9gique tourn\u00e9e vers la desserte de niches r\u00e9gionales, souvent d\u00e9laiss\u00e9es par les op\u00e9rateurs traditionnels.<\/p>\n\n<p class=\"wp-block-paragraph\">Cette \u00e9volution ne se limite pas aux lignes a\u00e9riennes africaines : l&rsquo;exemple sud-africain inspire d&rsquo;autres r\u00e9gions du monde, confront\u00e9es \u00e0 des probl\u00e9matiques similaires en termes d\u2019infrastructures a\u00e9roportuaires et de priorit\u00e9s environnementales. De ce fait, le survol \u00e0 Cape Town r\u00e9sonne aussi comme un symbole de la diversification au sein de l\u2019industrie a\u00e9ronautique mondiale, qui tend \u00e0 int\u00e9grer davantage de <strong>marques a\u00e9ronautiques<\/strong> alternatives.<\/p>\n\n<h2 class=\"wp-block-heading\">Un contexte a\u00e9rien mondial en mutation : p\u00e9nurie de k\u00e9ros\u00e8ne et diversification des flottes<\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019aviation commerciale traverse actuellement une p\u00e9riode de transition majeure. Alors que la hausse des prix du carburant et la p\u00e9nurie mondiale de k\u00e9ros\u00e8ne inqui\u00e8tent les compagnies a\u00e9riennes, la diversification des flottes est devenue une n\u00e9cessit\u00e9 pour assurer la viabilit\u00e9 des transports a\u00e9riens. Les avions de ligne comme ceux produits par Embraer repr\u00e9sentent une r\u00e9ponse adapt\u00e9e \u00e0 ces enjeux, offrant une meilleure efficience \u00e9nerg\u00e9tique sur les trajets courts et moyens.<\/p>\n\n<p class=\"wp-block-paragraph\">Cette situation est soulign\u00e9e par les pr\u00e9occupations r\u00e9centes relay\u00e9es dans plusieurs r\u00e9gions, notamment en Europe, o\u00f9 certains a\u00e9roports r\u00e9gionaux sont en premi\u00e8re ligne face aux difficult\u00e9s d\u2019approvisionnement en carburant. Ces contraintes incitent les acteurs du transport a\u00e9rien \u00e0 repenser leurs strat\u00e9gies et \u00e0 privil\u00e9gier des appareils moins gourmands, capables de maintenir des services essentiels m\u00eame dans des conditions \u00e9conomiques tendues. Des articles comme celui sur <a href=\"https:\/\/www.laeroport.fr\/news\/penurie-de-kerosene-les-compagnies-aeriennes-craignent-limmobilisation-prochaine-des-avions\/\">la p\u00e9nurie de k\u00e9ros\u00e8ne<\/a> illustrent ces d\u00e9fis concrets auxquels font face les transporteurs aujourd\u2019hui.<\/p>\n\n<p class=\"wp-block-paragraph\">En somme, cette tendance encourage une r\u00e9volution progressiste dans la composition des flottes mondiales, permettant de r\u00e9duire les \u00e9missions et d\u2019optimiser les co\u00fbts. Tandis que Boeing et Airbus travaillent sur des projets de grande envergure, notamment des avions \u00e0 faible \u00e9mission, d\u2019autres constructeurs s\u2019illustrent dans la cr\u00e9ation d\u2019appareils plus l\u00e9gers et plus adapt\u00e9s \u00e0 la r\u00e9alit\u00e9 op\u00e9rationnelle des compagnies r\u00e9gionales et \u00e9mergentes.<\/p>\n\n<h3 class=\"wp-block-heading\">Les avantages strat\u00e9giques dans le transport a\u00e9rien r\u00e9gional<\/h3>\n\n<ul class=\"wp-block-list\"><li><strong>Flexibilit\u00e9 accrue<\/strong> gr\u00e2ce \u00e0 des avions qui peuvent desservir des pistes plus courtes et moins \u00e9quip\u00e9es.<\/li><li><strong>Co\u00fbts op\u00e9rationnels moindres<\/strong>, en particulier au regard de la consommation de carburant et des frais d\u2019entretien.<\/li><li><strong>Adaptation aux march\u00e9s \u00e9mergents<\/strong> souvent situ\u00e9s en zones moins dens\u00e9ment peupl\u00e9es ou en pleine expansion \u00e9conomique.<\/li><li><strong>Capacit\u00e9 \u00e0 maintenir la fr\u00e9quence des vols<\/strong> malgr\u00e9 les contraintes d\u2019approvisionnement \u00e9nerg\u00e9tique.<\/li><li><strong>Potentiel d\u2019int\u00e9gration dans des r\u00e9seaux multimodaux<\/strong> comprenant des liaisons terrestres et maritimes, comme observ\u00e9 avec les strat\u00e9gies innovantes d\u2019Airbus et Boeing.<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\">Entre spectacle a\u00e9rien et avanc\u00e9es technologiques : la place grandissante des marques alternatives dans l\u2019aviation commerciale<\/h2>\n\n<p class=\"wp-block-paragraph\">Le survol en formation des deux avions de ligne hors norme au-dessus du stade de rugby a mis en lumi\u00e8re une facette rarement m\u00e9diatis\u00e9e du transport a\u00e9rien : celle des constructeurs tiers capables de rivaliser avec les poids lourds que sont Boeing et Airbus. Cet \u00e9v\u00e9nement illustre la mont\u00e9e en puissance d\u2019entreprises capables d\u2019apporter des solutions innovantes, comp\u00e9titives et adapt\u00e9es \u00e0 des besoins pr\u00e9cis.<\/p>\n\n<p class=\"wp-block-paragraph\">Dans un march\u00e9 tr\u00e8s concurrentiel, ces marques \u00e9tonnantes b\u00e9n\u00e9ficient surtout de l&rsquo;\u00e9volution des attentes en mati\u00e8re de transport a\u00e9rien, o\u00f9 la flexibilit\u00e9, la rentabilit\u00e9 et la r\u00e9duction des nuisances environnementales prennent une importance majeure. Par ailleurs, les innovations continues dans le domaine technologique offrent un terrain de jeu favorable pour ces fabricants, qui peuvent plus facilement int\u00e9grer des avanc\u00e9es gr\u00e2ce \u00e0 des mod\u00e8les d\u2019affaires souples et r\u00e9actifs.<\/p>\n\n<p class=\"wp-block-paragraph\">Les compagnies comme Airlink illustrent \u00e9galement cette tendance, en choisissant d\u2019int\u00e9grer \u00e0 leur flotte des avions performants et originaux, capables de renforcer leur position sur des lignes concurrentielles tout en offrant un haut niveau de s\u00e9curit\u00e9 et de confort. De nombreux experts anticipent d\u2019ailleurs que cette diversification jouera un r\u00f4le cl\u00e9 dans l\u2019\u00e9volution future des flux a\u00e9riens mondiaux, en particulier dans les r\u00e9gions en croissance rapide.<\/p>\n\n<p class=\"wp-block-paragraph\">La sc\u00e8ne de Cape Town n\u2019est donc pas qu\u2019un simple tableau spectaculaire mais un indicateur important des transformations qui red\u00e9finissent l\u2019aviation commerciale universelle, mettant en avant des constructeurs alternatifs et surtout des avions de ligne capables d\u2019\u00e9voluer dans des contextes exigeants. Avec cette d\u00e9monstration hors du commun, la marque Embraer prouve que le jeu a\u00e9ronautique ne se r\u00e9sume plus seulement \u00e0 un duel entre Boeing et Airbus, mais s\u2019enrichit gr\u00e2ce \u00e0 l\u2019essor de nouveaux acteurs innovants.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 Cape Town, un \u00e9v\u00e9nement spectaculaire a boulevers\u00e9 les habitu\u00e9s du rugby et les amateurs d&rsquo;aviation commerciale. Deux avions de ligne sont pass\u00e9s \u00e0 seulement une douzaine de m\u00e8tres au-dessus du toit du DLC Stadium, venant fr\u00f4ler un public mass\u00e9 pour le match opposant les Springboks aux All Blacks. Ce survol \u00e9tonnant, qui a eu [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-aeroports"],"_links":{"self":[{"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/posts\/8516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/comments?post=8516"}],"version-history":[{"count":0,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/posts\/8516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/media\/8514"}],"wp:attachment":[{"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/media?parent=8516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/categories?post=8516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laeroport.fr\/news\/wp-json\/wp\/v2\/tags?post=8516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}